{"id":18,"count":1,"description":"","link":"https:\/\/universvoyage.com\/en\/tag\/chalet\/","name":"Chalet","slug":"chalet","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Chalet Archives - Univers Voyage<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/universvoyage.com\/en\/tag\/chalet\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Chalet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/universvoyage.com\/en\/tag\/chalet\/\" \/>\n<meta property=\"og:site_name\" content=\"Univers Voyage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@UniversVoyage\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/universvoyage.com\\\/tag\\\/chalet\\\/\",\"url\":\"https:\\\/\\\/universvoyage.com\\\/tag\\\/chalet\\\/\",\"name\":\"Chalet Archives - Univers Voyage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/universvoyage.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/universvoyage.com\\\/tag\\\/chalet\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/universvoyage.com\\\/tag\\\/chalet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/universvoyage.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chalet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/universvoyage.com\\\/#website\",\"url\":\"https:\\\/\\\/universvoyage.com\\\/\",\"name\":\"Univers Voyage\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/universvoyage.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Chalet Archives - Univers Voyage","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/universvoyage.com\/en\/tag\/chalet\/","og_locale":"en_GB","og_type":"article","og_title":"Archives des Chalet","og_url":"https:\/\/universvoyage.com\/en\/tag\/chalet\/","og_site_name":"Univers Voyage","twitter_card":"summary_large_image","twitter_site":"@UniversVoyage","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/universvoyage.com\/tag\/chalet\/","url":"https:\/\/universvoyage.com\/tag\/chalet\/","name":"Chalet Archives - Univers Voyage","isPartOf":{"@id":"https:\/\/universvoyage.com\/#website"},"breadcrumb":{"@id":"https:\/\/universvoyage.com\/tag\/chalet\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/universvoyage.com\/tag\/chalet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/universvoyage.com\/"},{"@type":"ListItem","position":2,"name":"Chalet"}]},{"@type":"WebSite","@id":"https:\/\/universvoyage.com\/#website","url":"https:\/\/universvoyage.com\/","name":"Travel Universe","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/universvoyage.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/universvoyage.com\/en\/wp-json\/wp\/v2\/tags\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/universvoyage.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/universvoyage.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/universvoyage.com\/en\/wp-json\/wp\/v2\/posts?tags=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}